{"id":37,"date":"2018-03-14T12:38:33","date_gmt":"2018-03-14T03:38:33","guid":{"rendered":"https:\/\/company.central.co.jp\/en\/?page_id=37"},"modified":"2025-08-25T11:38:33","modified_gmt":"2025-08-25T02:38:33","slug":"highlight","status":"publish","type":"page","link":"https:\/\/company.central.co.jp\/en\/investor\/highlight\/","title":{"rendered":"highlight"},"content":{"rendered":"<div class=\"wrapper\">\r\n<section class=\"contents\">\r\n<div class=\"kvWrapper\">\r\n<div class=\"kv\">\r\n<h1><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"261\" class=\"pc\" alt=\"Financial Highlights\" src=\"https:\/\/company.central.co.jp\/en\/wp-content\/themes\/company_en_res\/investor\/highlight\/img\/mainImg.jpg\" \/> <img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"158\" class=\"sp\" alt=\"Financial Highlights\" src=\"https:\/\/company.central.co.jp\/en\/wp-content\/themes\/company_en_res\/investor\/highlight\/img\/mainImg_sp.jpg\" \/><\/h1>\r\n<\/div>\r\n<\/div>\r\n<ul class=\"clearfix\" id=\"breadlist\">\r\n\t<li><a href=\"\/en\/\">TOP<\/a>\u00a0\u00a0&gt;<\/li>\r\n\t<li><a href=\"\/en\/investor\/\">IR Library<\/a>\u00a0\u00a0&gt;<\/li>\r\n\t<li>Financial Highlights<\/li>\r\n<!-- breadlist--><\/ul>\r\n<div class=\"ctContentsWrapper\">\r\n<div class=\"ctContents\">\r\n<div class=\"highlightWrapper\">\r\n<section class=\"highlight\">\r\n<p>Consolidated financial results for the past six periods are available.<\/p>\r\n<div class=\"scroll\">\r\n<table style=\"width: 100.629%;height: 624px\">\r\n<tbody>\r\n<tr style=\"height: 24px\">\r\n<th style=\"width: 20.2318%;height: 24px\">\u00a0<\/th>\r\n<td style=\"width: 12.9999%;height: 24px;text-align: center\">End of March 2020<\/td>\r\n<td style=\"width: 12.4449%;height: 24px;text-align: center\">End of March 2021<\/td>\r\n<td style=\"width: 12.7867%;height: 24px;text-align: center\">End of March 2022<\/td>\r\n<td style=\"width: 12.9999%;height: 24px;text-align: center\">End of March 2023<\/td>\r\n<td style=\"width: 12.4449%;height: 24px;text-align: center\">End of March 2024<\/td>\r\n<td style=\"width: 12.7867%;height: 24px;text-align: center\">End of March 2025<\/td>\r\n<\/tr>\r\n<tr style=\"height: 56px\">\r\n<th style=\"width: 20.2318%;height: 56px\">Annual Turnover <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 56px\">\r\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\">53,386<\/span><\/p>\r\n<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 56px\">36,027<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 56px\">40,338<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>43,602<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>45,379<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>46,595<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Operating income <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">3,814<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">878<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">1,517<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>1,850<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>2,653<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>1,946<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Ordinary income <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">3,374<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">752<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">2,595<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>1,346<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>2,181<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>1,524<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Profit <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">2,138<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">-2,363<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">1,540<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>793<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>1,160<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>1,359<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Earnings per share <br \/>\r\n(yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">190.37<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">-211.03<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">137.52<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>70.86<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>103.62<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>121.37<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 72px\">\r\n<th style=\"width: 20.2318%;height: 72px\">Number of shares issued and outstanding <br \/>\r\n(stock)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<td style=\"width: 12.9999%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 72px\">11,466,300<\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Total assets <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">44,732<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">43,746<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">44,777<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>42,565<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>41,628<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>41,153<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Net assets <br \/>\r\n(million yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">24,738<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">22,144<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">23,540<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>23,901<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>24,823<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>25,840<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Net assets per share <br \/>\r\n(yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">2,207.06<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">1,975.95<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">2,100.70<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>2,133.28<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>2,216.27<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>2,307.04<\/span><\/td>\r\n<\/tr>\r\n<tr style=\"height: 48px\">\r\n<th style=\"width: 20.2318%;height: 48px\">Dividend per share <br \/>\r\n(yen)<\/th>\r\n<td style=\"width: 12.9999%;text-align: center;height: 48px\">57.0<\/td>\r\n<td style=\"width: 12.4449%;text-align: center;height: 48px\">5.0<\/td>\r\n<td style=\"width: 12.7867%;text-align: center;height: 48px\">41.0<\/td>\r\n<td style=\"width: 12.9999%;text-align: center\"><span>31.00<\/span><\/td>\r\n<td style=\"width: 12.4449%;text-align: center\"><span>36.00<\/span><\/td>\r\n<td style=\"width: 12.7867%;text-align: center\"><span>50.00<\/span><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\r\n<\/section>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>\r\n<\/div>","protected":false},"excerpt":{"rendered":"TOP\u00a0\u00a0&gt; IR Library\u00a0\u00a0&gt; Financial Highlights Consolidated financial results for the past six periods are av [&hellip;]","protected":false},"author":14,"featured_media":0,"parent":33,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"page-highlight.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-37","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:05:48","action":"change-status","newStatus":"private","terms":[],"taxonomy":""},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/pages\/37"}],"collection":[{"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":14,"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/pages\/37\/revisions"}],"predecessor-version":[{"id":217,"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/pages\/37\/revisions\/217"}],"up":[{"embeddable":true,"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/pages\/33"}],"wp:attachment":[{"href":"https:\/\/company.central.co.jp\/en\/wp-json\/wp\/v2\/media?parent=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}